{"id":150,"date":"2016-02-03T20:37:12","date_gmt":"2016-02-03T18:37:12","guid":{"rendered":"https:\/\/sandbox.favethemes.com\/houzez\/?post_type=houzez_agent&#038;p=150"},"modified":"2022-10-24T14:58:09","modified_gmt":"2022-10-24T12:58:09","slug":"jose-valdivia","status":"publish","type":"houzez_agent","link":"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/","title":{"rendered":"Jose Valdivia"},"content":{"rendered":"","protected":false},"featured_media":3411,"parent":0,"menu_order":0,"template":"","agent_category":[],"agent_city":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"InmoClever - Tu inmobiliaria de confianza Valencia, Malaga, Marbella...\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Jose Valdivia - InmoClever\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.inmoclever.com\/wp-content\/uploads\/2022\/09\/logo_200_mobile.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.inmoclever.com\/wp-content\/uploads\/2022\/09\/logo_200_mobile.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"18\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-03T18:37:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-10-24T12:58:09+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/inmoclever\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Jose Valdivia - InmoClever\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.inmoclever.com\/wp-content\/uploads\/2022\/09\/logo_200_mobile.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/index.php\\\/agente\\\/jose-valdivia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.inmoclever.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.inmoclever.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/index.php\\\/agente\\\/#listItem\",\"name\":\"Agentes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/index.php\\\/agente\\\/#listItem\",\"position\":2,\"name\":\"Agentes\",\"item\":\"https:\\\/\\\/www.inmoclever.com\\\/index.php\\\/agente\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/index.php\\\/agente\\\/jose-valdivia\\\/#listItem\",\"name\":\"Jose Valdivia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.inmoclever.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/index.php\\\/agente\\\/jose-valdivia\\\/#listItem\",\"position\":3,\"name\":\"Jose Valdivia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/index.php\\\/agente\\\/#listItem\",\"name\":\"Agentes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/#organization\",\"name\":\"InmoClever\",\"description\":\"Tu inmobiliaria de confianza Valencia, Malaga, Marbella...\",\"url\":\"https:\\\/\\\/www.inmoclever.com\\\/\",\"telephone\":\"+34620236379\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.inmoclever.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/logo_200_mobile.png\",\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/index.php\\\/agente\\\/jose-valdivia\\\/#organizationLogo\",\"width\":200,\"height\":18},\"image\":{\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/index.php\\\/agente\\\/jose-valdivia\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/inmoclever\",\"https:\\\/\\\/instagram.com\\\/inmoclever\",\"https:\\\/\\\/youtube.com\\\/inmoclever\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/index.php\\\/agente\\\/jose-valdivia\\\/#webpage\",\"url\":\"https:\\\/\\\/www.inmoclever.com\\\/index.php\\\/agente\\\/jose-valdivia\\\/\",\"name\":\"Jose Valdivia - InmoClever\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/index.php\\\/agente\\\/jose-valdivia\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.inmoclever.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/ipad_retina_fav.png\",\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/index.php\\\/agente\\\/jose-valdivia\\\/#mainImage\",\"width\":144,\"height\":114},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/index.php\\\/agente\\\/jose-valdivia\\\/#mainImage\"},\"datePublished\":\"2016-02-03T20:37:12+02:00\",\"dateModified\":\"2022-10-24T14:58:09+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/#website\",\"url\":\"https:\\\/\\\/www.inmoclever.com\\\/\",\"name\":\"InmoClever\",\"description\":\"Tu inmobiliaria de confianza Valencia, Malaga, Marbella...\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.inmoclever.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Jose Valdivia - InmoClever","description":"","canonical_url":"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.inmoclever.com#listItem","position":1,"name":"Home","item":"https:\/\/www.inmoclever.com","nextItem":{"@type":"ListItem","@id":"https:\/\/www.inmoclever.com\/index.php\/agente\/#listItem","name":"Agentes"}},{"@type":"ListItem","@id":"https:\/\/www.inmoclever.com\/index.php\/agente\/#listItem","position":2,"name":"Agentes","item":"https:\/\/www.inmoclever.com\/index.php\/agente\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/#listItem","name":"Jose Valdivia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.inmoclever.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/#listItem","position":3,"name":"Jose Valdivia","previousItem":{"@type":"ListItem","@id":"https:\/\/www.inmoclever.com\/index.php\/agente\/#listItem","name":"Agentes"}}]},{"@type":"Organization","@id":"https:\/\/www.inmoclever.com\/#organization","name":"InmoClever","description":"Tu inmobiliaria de confianza Valencia, Malaga, Marbella...","url":"https:\/\/www.inmoclever.com\/","telephone":"+34620236379","logo":{"@type":"ImageObject","url":"https:\/\/www.inmoclever.com\/wp-content\/uploads\/2022\/09\/logo_200_mobile.png","@id":"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/#organizationLogo","width":200,"height":18},"image":{"@id":"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/inmoclever","https:\/\/instagram.com\/inmoclever","https:\/\/youtube.com\/inmoclever"]},{"@type":"WebPage","@id":"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/#webpage","url":"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/","name":"Jose Valdivia - InmoClever","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.inmoclever.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.inmoclever.com\/wp-content\/uploads\/2022\/09\/ipad_retina_fav.png","@id":"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/#mainImage","width":144,"height":114},"primaryImageOfPage":{"@id":"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/#mainImage"},"datePublished":"2016-02-03T20:37:12+02:00","dateModified":"2022-10-24T14:58:09+02:00"},{"@type":"WebSite","@id":"https:\/\/www.inmoclever.com\/#website","url":"https:\/\/www.inmoclever.com\/","name":"InmoClever","description":"Tu inmobiliaria de confianza Valencia, Malaga, Marbella...","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.inmoclever.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"InmoClever - Tu inmobiliaria de confianza Valencia, Malaga, Marbella...","og:type":"article","og:title":"Jose Valdivia - InmoClever","og:url":"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/","og:image":"https:\/\/www.inmoclever.com\/wp-content\/uploads\/2022\/09\/logo_200_mobile.png","og:image:secure_url":"https:\/\/www.inmoclever.com\/wp-content\/uploads\/2022\/09\/logo_200_mobile.png","og:image:width":200,"og:image:height":18,"article:published_time":"2016-02-03T18:37:12+00:00","article:modified_time":"2022-10-24T12:58:09+00:00","article:publisher":"https:\/\/facebook.com\/inmoclever","twitter:card":"summary_large_image","twitter:title":"Jose Valdivia - InmoClever","twitter:image":"https:\/\/www.inmoclever.com\/wp-content\/uploads\/2022\/09\/logo_200_mobile.png"},"aioseo_meta_data":{"post_id":"150","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-09-21 10:15:04","updated":"2025-06-04 02:49:23","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.inmoclever.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.inmoclever.com\/index.php\/agente\/\" title=\"Agentes\">Agentes<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tJose Valdivia\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.inmoclever.com"},{"label":"Agentes","link":"https:\/\/www.inmoclever.com\/index.php\/agente\/"},{"label":"Jose Valdivia","link":"https:\/\/www.inmoclever.com\/index.php\/agente\/jose-valdivia\/"}],"agent_meta":{"_vc_post_settings":["a:1:{s:10:\"vc_grid_id\";a:0:{}}"],"fave_agent_position":["Director Comercial"],"fave_agent_company":["Inmoclever"],"fave_agent_mobile":["+34 637 374 451"],"fave_agent_facebook":["#"],"fave_agent_twitter":["#"],"fave_agent_linkedin":["#"],"fave_agent_googleplus":["#"],"fave_agent_youtube":["#"],"fave_agent_email":["valdi@inmoclever.com"],"fave_agent_des":["Agente Inmoclever"],"fave_agent_specialties":["Compraventa, Tasaciones y Captaciones"],"fave_agent_language":["Espa\u00f1ol"],"fave_agent_visible":["0"],"fave_agent_whatsapp":["321 456 9874"],"_edit_lock":["1666616290:1"],"_edit_last":["1"],"fave_agent_website":["https:\/\/www.inmoclever.com"],"fave_agent_agencies":["3437"],"_aioseo_title":[null],"_aioseo_description":[null],"_aioseo_keywords":[""],"_aioseo_og_title":[null],"_aioseo_og_description":[null],"_aioseo_og_article_section":[""],"_aioseo_og_article_tags":[""],"_aioseo_twitter_title":[null],"_aioseo_twitter_description":[null],"om_disable_all_campaigns":[""],"_thumbnail_id":["3411"],"fave_agent_logo":["3411"]},"_links":{"self":[{"href":"https:\/\/www.inmoclever.com\/index.php\/wp-json\/wp\/v2\/agents\/150"}],"collection":[{"href":"https:\/\/www.inmoclever.com\/index.php\/wp-json\/wp\/v2\/agents"}],"about":[{"href":"https:\/\/www.inmoclever.com\/index.php\/wp-json\/wp\/v2\/types\/houzez_agent"}],"version-history":[{"count":1,"href":"https:\/\/www.inmoclever.com\/index.php\/wp-json\/wp\/v2\/agents\/150\/revisions"}],"predecessor-version":[{"id":3440,"href":"https:\/\/www.inmoclever.com\/index.php\/wp-json\/wp\/v2\/agents\/150\/revisions\/3440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inmoclever.com\/index.php\/wp-json\/wp\/v2\/media\/3411"}],"wp:attachment":[{"href":"https:\/\/www.inmoclever.com\/index.php\/wp-json\/wp\/v2\/media?parent=150"}],"wp:term":[{"taxonomy":"agent_category","embeddable":true,"href":"https:\/\/www.inmoclever.com\/index.php\/wp-json\/wp\/v2\/agent_category?post=150"},{"taxonomy":"agent_city","embeddable":true,"href":"https:\/\/www.inmoclever.com\/index.php\/wp-json\/wp\/v2\/agent_city?post=150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}